{"id":17031,"date":"2024-08-23T17:01:01","date_gmt":"2024-08-23T17:01:01","guid":{"rendered":"https:\/\/garnetfinancial.ca\/les-femmes-et-les-planificateurs-financiers-comprendre-le-point-de-vue-de-la-cliente\/"},"modified":"2024-08-26T17:48:29","modified_gmt":"2024-08-26T17:48:29","slug":"les-femmes-et-les-planificateurs-financiers-comprendre-le-point-de-vue-de-la-cliente","status":"publish","type":"post","link":"https:\/\/garnetfinancial.ca\/fr\/les-femmes-et-les-planificateurs-financiers-comprendre-le-point-de-vue-de-la-cliente\/","title":{"rendered":"Les femmes et les planificateurs financiers&#8230; Comprendre le point de vue de la cliente"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17031\" class=\"elementor elementor-17031 elementor-16302\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5081cd e-flex e-con-boxed e-con e-parent\" data-id=\"6f5081cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c0f9d32 elementor-widget elementor-widget-text-editor\" data-id=\"6c0f9d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La bonne nouvelle : Aujourd&rsquo;hui, les femmes canadiennes ont plus de pouvoir \u00e9conomique, cependant, alors qu&rsquo;elles gagnent en influence dans la prise de d\u00e9cision financi\u00e8re du m\u00e9nage, une \u00e9tude de Mintel, une agence d&rsquo;intelligence \u00e9conomique, r\u00e9v\u00e8le que 32% des femmes canadiennes ont un pouvoir \u00e9conomique sup\u00e9rieur \u00e0 celui des hommes.<span style=\"color: #8b2332;\"><strong>  des femmes craignent de prendre des d\u00e9cisions financi\u00e8res en raison d&rsquo;un manque de connaissances financi\u00e8res.<br \/>\nL&rsquo;\u00e9tude r\u00e9v\u00e8le \u00e9galement que   <\/strong><\/span>36% souhaiteraient \u00eatre plus confiants dans la prise de ces d\u00e9cisions.<\/p>\n<p>Ainsi, m\u00eame si les femmes d\u00e9tiennent plus de pouvoir financier que jamais, elles ne sont toujours pas \u00e0 l&rsquo;aise pour parler de finances, pour prendre des d\u00e9cisions financi\u00e8res importantes et m\u00eame pour jouer un r\u00f4le cl\u00e9 dans la prise de d\u00e9cisions financi\u00e8res qui les concernent directement, elles et leur argent.<br \/>\nBeaucoup se disent intimid\u00e9es par le secteur financier. <\/p>\n<p>Pourquoi en est-il ainsi ?<br \/>\nTraditionnellement, les planificateurs et les conseillers financiers ont l&rsquo;habitude de traiter avec des hommes et ils sont habitu\u00e9s \u00e0 faire des affaires d&rsquo;une certaine mani\u00e8re.<br \/>\nLes femmes ne sont pas en mesure de s&rsquo;adapter \u00e0 ce style de travail.<br \/>\nC&rsquo;est comme si certains conseillers financiers n&rsquo;avaient pas appris \u00e0 adapter leur style de communication et, \u00e0 cet \u00e9gard, il y a un d\u00e9calage entre le secteur financier en g\u00e9n\u00e9ral et la fa\u00e7on dont les femmes aiment travailler.   <\/p>\n<p>Lorsqu&rsquo;il s&rsquo;agit de discuter avec des planificateurs financiers, certaines femmes disent qu&rsquo;elles ne sont pas satisfaites :<\/p>\n<ul>\n<li>sont intimid\u00e9s<\/li>\n<li>Se sentir mal \u00e0 l&rsquo;aise<\/li>\n<li>Ils ont l&rsquo;impression qu&rsquo;on leur parle avec condescendance<\/li>\n<li>Ne vous sentez pas respect\u00e9<\/li>\n<li>sont facilement d\u00e9bord\u00e9s<\/li>\n<\/ul>\n<h4><em><strong>Quelles sont les \u00e9tapes qu&rsquo;une femme devrait suivre pour s&rsquo;engager avec un planificateur ?<br \/>\nTout d&rsquo;abord, les femmes doivent savoir que la relation avec leur planificateur financier est comme toute autre relation.<br \/>\nIl doit y avoir un respect mutuel et une communication ais\u00e9e.  <\/strong><\/em><\/h4>\n<\/p>\n<p>Avant de choisir votre planificateur financier, posez-vous la question suivante : \u00ab\u00a0Qu&rsquo;est-ce que je recherche ? Quel est le r\u00e9sultat que je souhaite obtenir ? Avec quel type de personne ai-je envie de travailler ? Quelqu&rsquo;un d&rsquo;attentif ou de professionnel ? Quelqu&rsquo;un qui posera beaucoup de questions pertinentes et qui prendra le temps d&rsquo;expliquer ? Ou quelqu&rsquo;un qui prend l&rsquo;initiative et fournit des recommandations ?<\/p>\n<p>Il devrait y avoir un certain niveau de confort et une connexion.<br \/>\nAucune femme (ni aucun homme d&rsquo;ailleurs) ne doit se sentir intimid\u00e9e par ce que propose le secteur.<br \/>\nLorsqu&rsquo;ils ne comprennent pas quelque chose, ils doivent se sentir libres de poser des questions.<br \/>\nSi les r\u00e9ponses se r\u00e9sument \u00e0 un jargon industriel, demandez \u00e0 votre planificateur financier de vous l&rsquo;expliquer en termes simples.   <\/p>\n<p>En prenant le contr\u00f4le et en posant les bonnes questions, vous devenez autonome dans le processus de planification financi\u00e8re.<br \/>\nLes femmes ne sont plus li\u00e9es par les anciennes normes et peuvent donner la priorit\u00e9 \u00e0 leur avenir financier. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La bonne nouvelle : Aujourd&rsquo;hui, les femmes canadiennes ont plus de pouvoir \u00e9conomique. Cependant, alors qu&rsquo;elles gagnent en influence dans les d\u00e9cisions financi\u00e8res du m\u00e9nage, une \u00e9tude de Mintel, une agence d&rsquo;intelligence \u00e9conomique, r\u00e9v\u00e8le que 32 % des femmes craignent de prendre des d\u00e9cisions financi\u00e8res en raison d&rsquo;un manque de connaissances en la mati\u00e8re.<br \/>\nL&rsquo;\u00e9tude r\u00e9v\u00e8le \u00e9galement que 36 % d&rsquo;entre elles souhaiteraient \u00eatre plus s\u00fbres d&rsquo;elles pour prendre ces d\u00e9cisions. <\/p>\n","protected":false},"author":1,"featured_media":17111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[199],"tags":[],"class_list":["post-17031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financial-planner"],"_links":{"self":[{"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/posts\/17031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/comments?post=17031"}],"version-history":[{"count":0,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/posts\/17031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/media\/17111"}],"wp:attachment":[{"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/media?parent=17031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/categories?post=17031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garnetfinancial.ca\/fr\/wp-json\/wp\/v2\/tags?post=17031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}